{"id":17514,"date":"2024-03-01T11:47:52","date_gmt":"2024-03-01T09:47:52","guid":{"rendered":"https:\/\/diskitips1x2.co.za\/?p=17514"},"modified":"2024-03-01T11:47:52","modified_gmt":"2024-03-01T09:47:52","slug":"soccer-10-payouts-thu-29-feb","status":"publish","type":"post","link":"https:\/\/diskitips1x2.co.za\/index.php\/2024\/03\/01\/soccer-10-payouts-thu-29-feb\/","title":{"rendered":"Soccer 10 Payouts  Thu 29 Feb"},"content":{"rendered":"<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<p>Soccer 10 Payouts<\/p>\n<p>Thu 29 Feb<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<p><strong>How to Play Soccer 10: <\/strong><\/p>\n<p><strong>Correctly predict the outcome of all (10) fixtures to win the jackpot*<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div><a href=\"https:\/\/www.betway.co.za\/?register=1&amp;btag=P57206-PR22239-CM56544-TS176802\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-16605\" src=\"https:\/\/diskitips1x2.co.za\/wp-content\/uploads\/2023\/12\/Betway-Datafree-Signup.png\" alt=\"\" width=\"759\" height=\"490\" srcset=\"https:\/\/diskitips1x2.co.za\/wp-content\/uploads\/2023\/12\/Betway-Datafree-Signup.png 759w, https:\/\/diskitips1x2.co.za\/wp-content\/uploads\/2023\/12\/Betway-Datafree-Signup-300x194.png 300w\" sizes=\"(max-width: 759px) 100vw, 759px\" \/><\/a><\/div>\n<div>\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<p>Register &amp; Play Today&#8217;s Code<\/p>\n<p>With A Free R25 Bet<\/p>\n<p><a href=\"https:\/\/www.betway.co.za\/?register=1&amp;btag=P57206-PR22239-CM56544-TS176802\"><strong>Booking code U19A5DA97<\/strong><\/a><\/p>\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<p>Soccer 10 Payouts<\/p>\n<div class=\"pooldateindicator4R\">Thu 29 Feb\u00a0&#8211; S10\u00a0V3<\/div>\n<table class=\"pooltable\">\n<tbody>\n<tr>\n<th>Match<\/th>\n<th>Team A<\/th>\n<th>Score<\/th>\n<th>Team B<\/th>\n<\/tr>\n<tr>\n<td class=\"bold\">M1<\/td>\n<td>Ironi Kiryat Shmona<\/td>\n<td>2 &#8211; 1<\/td>\n<td class=\"righttext\">Hapoel Ramat HaSharon<\/td>\n<\/tr>\n<tr>\n<td class=\"bold\">M2<\/td>\n<td>Galatasaray<\/td>\n<td>0 &#8211; 2<\/td>\n<td class=\"righttext\">Fatih Karagumruk<\/td>\n<\/tr>\n<tr>\n<td class=\"bold\">M3<\/td>\n<td>Bnei Yehuda<\/td>\n<td>0 &#8211; 4<\/td>\n<td class=\"righttext\">Hapoel Petah Tikva<\/td>\n<\/tr>\n<tr>\n<td class=\"bold\">M4<\/td>\n<td>FC Sion<\/td>\n<td>2 &#8211; 1<\/td>\n<td class=\"righttext\">Young Boys<\/td>\n<\/tr>\n<tr>\n<td class=\"bold\">M5<\/td>\n<td>Antwerp<\/td>\n<td>3 &#8211; 0<\/td>\n<td class=\"righttext\">KV Oostende<\/td>\n<\/tr>\n<tr>\n<td class=\"bold\">M6<\/td>\n<td>Athletic Bilbao<\/td>\n<td>3 &#8211; 0<\/td>\n<td class=\"righttext\">Atletico Madrid<\/td>\n<\/tr>\n<tr>\n<td class=\"bold\">M7<\/td>\n<td>Sporting Lisbon<\/td>\n<td>2 &#8211; 1<\/td>\n<td class=\"righttext\">Benfica<\/td>\n<\/tr>\n<tr>\n<td class=\"bold\">M8<\/td>\n<td>Indep Rivadavia<\/td>\n<td>1 &#8211; 3<\/td>\n<td class=\"righttext\">Barracas Central<\/td>\n<\/tr>\n<tr>\n<td class=\"bold\">M9<\/td>\n<td>Atletico Huracan<\/td>\n<td>2 &#8211; 0<\/td>\n<td class=\"righttext\">Rosario Central<\/td>\n<\/tr>\n<tr>\n<td class=\"bold\">M10<\/td>\n<td>Colo Colo<\/td>\n<td>0 &#8211; 0<\/td>\n<td class=\"righttext\">Godoy Cruz<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"panel poolinformation\">Winning Combination:\u00a01\/3\/3\/1\/1\/1\/1\/3\/1\/2<br \/>\nStatus: Official<\/p>\n<div>Results: (9\/10)<br \/>\nNet 9\/10: R307,466.76<br \/>\nWinners:\u00a0405<br \/>\nDividend: R759.00<\/p>\n<\/div>\n<p>Results: (10\/10)<br \/>\nNet 10\/10: R1,229,867.05<br \/>\nWinners:\u00a013<br \/>\nDividend: R94,605.00<\/p><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>+++<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div>Register For DATA FREE BETTING NOW<\/div>\n<div><a href=\"https:\/\/www.betway.co.za\/?register=1&amp;btag=P57206-PR22239-CM56544-TS176802\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-16605\" src=\"https:\/\/diskitips1x2.co.za\/wp-content\/uploads\/2023\/12\/Betway-Datafree-Signup.png\" alt=\"\" width=\"759\" height=\"490\" srcset=\"https:\/\/diskitips1x2.co.za\/wp-content\/uploads\/2023\/12\/Betway-Datafree-Signup.png 759w, https:\/\/diskitips1x2.co.za\/wp-content\/uploads\/2023\/12\/Betway-Datafree-Signup-300x194.png 300w\" sizes=\"(max-width: 759px) 100vw, 759px\" \/><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"pooldateindicator4R\">\n<p><strong>Betting Tips Guide:<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<p style=\"text-align: center;\"><strong>We use the common 1X2 three-way bet type, with the draw option.<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Straight Selections are:<\/strong><\/p>\n<p style=\"text-align: center;\">1- Home Team to Win<br \/>\nX- Match to be a Draw<br \/>\n2- Away Team to Win<\/p>\n<p style=\"text-align: center;\"><strong>Doubles\/Triple Chance Selections cost extra<\/strong><\/p>\n<p style=\"text-align: center;\"><em>Triple Bets are only available on soccer pools* type games<\/em><\/p>\n<p style=\"text-align: center;\"><em><strong>Double Chance Betting<\/strong><\/em><\/p>\n<p style=\"text-align: center;\">Double chance covers <strong>two<\/strong> out of <strong>three<\/strong> (1X2) outcomes.<\/p>\n<p style=\"text-align: center;\">&#8216;1X&#8217; &#8211; stands for Home\/Draw<br \/>\n&#8216;X2&#8242; &#8211; stands for Draw\/Away<br \/>\n&#8217;12&#8217; &#8211; stands for Home\/Away<\/p>\n<p style=\"text-align: center;\"><em><strong>Triple Chance Betting<\/strong><\/em><\/p>\n<p style=\"text-align: center;\">Covers all three (1&#215;2) outcomes and <strong>closes<\/strong> the bet leg.<\/p>\n<p style=\"text-align: center;\">(1X2) \u2013 Home Win +Draw + Away Win<\/p>\n<p style=\"text-align: center;\"><em><strong>Banker Tips &amp; Code<\/strong><\/em><\/p>\n<p style=\"text-align: center;\">Soccer Banker Tips <strong>statistically<\/strong> speaking<\/p>\n<p style=\"text-align: center;\">have the best chance of winning<\/p>\n<p style=\"text-align: center;\">Combine several bet legs to make an (Accumulator)<\/p>\n<p style=\"text-align: center;\">Higher Odds = Bigger Payouts<\/p>\n<p style=\"text-align: center;\">More legs = More risk!<\/p>\n<p style=\"text-align: center;\">Tips, Odds &amp; Stats don&#8217;t play soccer!<\/p>\n<p style=\"text-align: center;\"><em><strong>Over\/Under (O\/U) Goals <\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><em><strong>Betting Explained:<\/strong><\/em><\/p>\n<p style=\"text-align: center;\">Bet on the <em><strong>TOTAL<\/strong><\/em> number of match goals<\/p>\n<p style=\"text-align: center;\">by either team after 90 mins<\/p>\n<p style=\"text-align: center;\"><strong>OVER GOALS BET MARKETS<\/strong><\/p>\n<p style=\"text-align: center;\">&#8211; O\/0.5 = 1+ goals<\/p>\n<p style=\"text-align: center;\">&#8211; O\/1.5 = 2+ goals<\/p>\n<p style=\"text-align: center;\">&#8211; O\/2.5 = 3+ goals<\/p>\n<p style=\"text-align: center;\">&#8211; O\/3.5 = 4+ goals<\/p>\n<p style=\"text-align: center;\">&#8211; O\/4.5 = 5+ goals<\/p>\n<p style=\"text-align: center;\"><strong>UNDER GOALS BET MARKETS<\/strong><\/p>\n<p style=\"text-align: center;\">&#8211; Under 0.5 = No goals (0-0)<\/p>\n<p style=\"text-align: center;\">&#8211; U\/1.5 = 1 or less goals<\/p>\n<p style=\"text-align: center;\">&#8211; U\/2.5 = 2 or less goals<\/p>\n<p style=\"text-align: center;\">&#8211; U\/3.5 = 3 or less goals<\/p>\n<p style=\"text-align: center;\">&#8211; U\/4.5 = 4 or less goals<\/p>\n<p style=\"text-align: center;\"><strong>BOTH TEAMS TO SCORE (BTTS) <\/strong><\/p>\n<p style=\"text-align: center;\"><strong><em>Betting Explained:<\/em><\/strong><\/p>\n<p style=\"text-align: center;\">BTTS is a popular betting market as it&#8217;s very easy to play<\/p>\n<p style=\"text-align: center;\">You bet either<strong> BTTS (Yes)<\/strong> or <strong>BTTS (No)<\/strong><\/p>\n<p style=\"text-align: center;\">Bet (<strong>Btts Yes<\/strong>) = Both teams need to score<\/p>\n<p style=\"text-align: center;\">Bet (<strong>Btts No<\/strong>) = one or both teams don&#8217;t score<\/p>\n<p style=\"text-align: center;\"><strong>Disclaimer:<\/strong><\/p>\n<p style=\"text-align: center;\">Anything can and does happen in sport, there are<strong> No Sure Bets<\/strong><\/p>\n<p style=\"text-align: center;\">Stats and data will help you win more often, the rest is up to Lady Luck!<\/p>\n<p style=\"text-align: center;\">This Web site does not offer (Bets) or (Lay Bets)<\/p>\n<p style=\"text-align: center;\">For (Entertainment Purposes Only) &#8211; Play At Your Own Risk*<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 16px; line-height: 1.5;\">This Web site cannot be held responsible <\/span><span style=\"font-size: 16px; line-height: 1.5;\">for any <\/span><span style=\"font-size: 16px; line-height: 1.5;\">damages or losses <\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 16px; line-height: 1.5;\">that could arise <\/span><span style=\"font-size: 16px; line-height: 1.5;\">from\u00a0<\/span><span style=\"font-size: 16px; line-height: 1.5;\">acting upon the information contained herein<\/span><\/p>\n<p style=\"text-align: center;\"><strong>Data changes constantly &#8211; All information is (subject to change)<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Always Double Check latest bet data before placing your bet*<\/strong><\/p>\n<p style=\"text-align: center;\">&#8212;<\/p>\n<p style=\"text-align: center;\">Play Responsibly &#8211; Never Play With Money You Can&#8217;t Afford To Lose!!!<\/p>\n<p style=\"text-align: center;\"><em>The South African Responsible Gambling Foundation (SARGF) <\/em><\/p>\n<p style=\"text-align: center;\"><em>provides Free Help &#8230; 006 008 Or SMS HELP To 076 675 0710 <\/em><\/p>\n<p style=\"text-align: center;\"><em>helpline@responsiblegambling.org.za<\/em><\/p>\n<\/div>\n<div>\n<p style=\"text-align: center;\"><em>This web site is for entertainment purposes (Only) <\/em><\/p>\n<p style=\"text-align: center;\"><em>AND HAS NO AFFILIATION TO TAB or National Lottery<\/em><\/p>\n<p style=\"text-align: center;\"><em><strong>Errors and omissions excepted (E&amp;OE) &#8211; Use this site as a guide at your own risk.<\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.betway.co.za\/offers\/huawei-giveaway\/?btag=P57206-PR22387-CM57443-TS1970593&amp;\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-7029\" src=\"https:\/\/diskitips1x2.co.za\/wp-content\/uploads\/2022\/10\/BW_SA_728_90_LuckyDraw_HuaweiGiveawy.gif\" alt=\"\" width=\"728\" height=\"90\" \/><\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Soccer 10 Payouts Thu 29 Feb How to Play Soccer 10: Correctly predict the outcome of all (10) fixtures to win the jackpot* Register &amp; <a class=\"mh-excerpt-more\" href=\"https:\/\/diskitips1x2.co.za\/index.php\/2024\/03\/01\/soccer-10-payouts-thu-29-feb\/\" title=\"Soccer 10 Payouts  Thu 29 Feb\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[17,13],"tags":[85],"class_list":["post-17514","post","type-post","status-publish","format-standard","hentry","category-soccer-10-results","category-soccer-results-payouts","tag-soccer-10-payouts"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","mh-magazine-lite-slider":"","mh-magazine-lite-content":"","mh-magazine-lite-large":"","mh-magazine-lite-medium":"","mh-magazine-lite-small":""},"author_info":{"display_name":"Admin","author_link":"https:\/\/diskitips1x2.co.za\/index.php\/author\/adminbliss1\/"},"category_info":"<a href=\"https:\/\/diskitips1x2.co.za\/index.php\/category\/soccer-results-payouts\/soccer-10-results\/\" rel=\"category tag\">Soccer 10 Results<\/a> <a href=\"https:\/\/diskitips1x2.co.za\/index.php\/category\/soccer-results-payouts\/\" rel=\"category tag\">Soccer Results &amp; Payouts<\/a>","tag_info":"Soccer Results &amp; Payouts","comment_count":"0","_links":{"self":[{"href":"https:\/\/diskitips1x2.co.za\/index.php\/wp-json\/wp\/v2\/posts\/17514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diskitips1x2.co.za\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diskitips1x2.co.za\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diskitips1x2.co.za\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/diskitips1x2.co.za\/index.php\/wp-json\/wp\/v2\/comments?post=17514"}],"version-history":[{"count":1,"href":"https:\/\/diskitips1x2.co.za\/index.php\/wp-json\/wp\/v2\/posts\/17514\/revisions"}],"predecessor-version":[{"id":17515,"href":"https:\/\/diskitips1x2.co.za\/index.php\/wp-json\/wp\/v2\/posts\/17514\/revisions\/17515"}],"wp:attachment":[{"href":"https:\/\/diskitips1x2.co.za\/index.php\/wp-json\/wp\/v2\/media?parent=17514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diskitips1x2.co.za\/index.php\/wp-json\/wp\/v2\/categories?post=17514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diskitips1x2.co.za\/index.php\/wp-json\/wp\/v2\/tags?post=17514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}